{"id":9079,"date":"2023-10-01T07:10:57","date_gmt":"2023-10-01T07:10:57","guid":{"rendered":"https:\/\/visitestepona.eu\/restaurante-la-escollera-estepona\/"},"modified":"2024-08-30T09:01:08","modified_gmt":"2024-08-30T09:01:08","slug":"restaurante-la-escollera-estepona","status":"publish","type":"post","link":"https:\/\/visitestepona.eu\/es\/restaurante-la-escollera-estepona\/","title":{"rendered":"Restaurante La Escollera Estepona"},"content":{"rendered":"\n<p>\u00a1Amantes del pescado!<br\/>No debes perd\u00e9rtelo si est\u00e1s en la hora de Estepona: justo en el puerto pesquero de Estepona, es &#8216;el lugar para estar&#8217;. Gracias a esta ubicaci\u00f3n perfecta cerca del puerto, trabajan en estrecha colaboraci\u00f3n con los pescadores locales de La Escollera y se encuentran entre los primeros en seleccionar sus peces inmediatamente despu\u00e9s de ser capturados.<br\/>El pescado con el que trabajan aqu\u00ed, que se prepara de diferentes maneras, es m\u00e1s fresco que fresco. \u00a1Y puedes probarlo!<br\/><br\/>No hacen reservas, van a tiempo y esperan el espa\u00f1ol con una bebida entre los muchos lugare\u00f1os hasta que te llaman para una mesa. Contempla la escena que ha tenido lugar aqu\u00ed durante m\u00e1s de 80 a\u00f1os, un zumbido de camareros suaves, zumbido espa\u00f1ol y mucho pescado fresco.  <\/p>\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"478\" data-id=\"9065\" src=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2023\/10\/10393886_712614338806390_7098815100219765719_n.jpg\" alt=\"VisitEstepona\" class=\"wp-image-9065\" title=\"\" srcset=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2023\/10\/10393886_712614338806390_7098815100219765719_n.jpg 640w, https:\/\/visitestepona.eu\/wp-content\/uploads\/2023\/10\/10393886_712614338806390_7098815100219765719_n-480x359.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 640px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" data-id=\"9067\" src=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2023\/10\/130720635_3623954174339044_1615075914567902763_n.jpg\" alt=\"VisitEstepona\" class=\"wp-image-9067\" title=\"\" srcset=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2023\/10\/130720635_3623954174339044_1615075914567902763_n.jpg 640w, https:\/\/visitestepona.eu\/wp-content\/uploads\/2023\/10\/130720635_3623954174339044_1615075914567902763_n-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 640px, 100vw\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"479\" data-id=\"9066\" src=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2023\/10\/121385682_3462306400503823_5117194402117343442_n.jpg\" alt=\"VisitEstepona\" class=\"wp-image-9066\" title=\"\" srcset=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2023\/10\/121385682_3462306400503823_5117194402117343442_n.jpg 640w, https:\/\/visitestepona.eu\/wp-content\/uploads\/2023\/10\/121385682_3462306400503823_5117194402117343442_n-480x359.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 640px, 100vw\" \/><\/figure>\n<\/figure>\n\n<p>C. Puerto Pesquero, 10, 29680 Estepona<br\/><a href=\"https:\/\/www.google.com\/search?q=escollera+estepona&amp;sca_esv=569812948&amp;rlz=1CANTKV_enNL1038NL1038&amp;ei=ixgZZbGvO9nBi-gPv5MN&amp;gs_ssp=eJzj4tZP1zcsSbMsyDK3MGC0UjGoSDFITjFLMjJIM0tOSUo2tzKoMLM0NTM3MrU0MjY3TU4xMPMSSi1Ozs_JSS1KVEgtLkktyM9LBADXOhV5&amp;oq=escollera+este&amp;gs_lp=Egxnd3Mtd2l6LXNlcnAiDmVzY29sbGVyYSBlc3RlKgIIADILEC4YgAQYxwEYrwEyBRAAGIAEMgYQABgWGB4yBhAAGBYYHjIGEAAYFhgeMgYQABgWGB4yCBAAGBYYHhgKMgYQABgWGB4yBhAAGBYYHjIGEAAYFhgeMhoQLhiABBjHARivARiXBRjcBBjeBBjgBNgBAkj-EVDLBViiCnABeAGQAQCYAaYBoAH0BKoBAzIuM7gBAcgBAPgBAcICChAAGEcY1gQYsAPCAgoQABiKBRiwAxhDwgIWEC4YigUYxwEYrwEYyAMYsAMYQ9gBAcICEBAuGIoFGMgDGLADGEPYAQHCAhwQLhiKBRjHARivARiYBRiZBRjIAxiwAxhD2AEBwgILEC4YrwEYxwEYgATCAhoQLhivARjHARiABBiXBRjcBBjeBBjgBNgBAsICCBAAGBYYHhgP4gMEGAAgQYgGAZAGEroGBggBEAEYCLoGBggCEAEYFA&amp;sclient=gws-wiz-serp#\" target=\"_blank\" rel=\"noopener\">+34 952 80 63 54<\/a><br\/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Amantes del pescado!No debes perd\u00e9rtelo si est\u00e1s en la hora de Estepona: justo en el puerto pesquero de Estepona, es &#8216;el lugar para estar&#8217;. Gracias a esta ubicaci\u00f3n perfecta cerca del puerto, trabajan en estrecha colaboraci\u00f3n con los pescadores locales de La Escollera y se encuentran entre los primeros en seleccionar sus peces inmediatamente despu\u00e9s\u2026 <a href=\"https:\/\/visitestepona.eu\/es\/restaurante-la-escollera-estepona\/\">Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":9054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[90,41],"tags":[125,126,96],"class_list":["post-9079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puntos-de-acceso-a-estepona","category-sin-categorizar","tag-almuerzo","tag-cena","tag-restaurantes-y-bares"],"acf":[],"_links":{"self":[{"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/posts\/9079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/comments?post=9079"}],"version-history":[{"count":2,"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/posts\/9079\/revisions"}],"predecessor-version":[{"id":227085,"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/posts\/9079\/revisions\/227085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/media\/9054"}],"wp:attachment":[{"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/media?parent=9079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/categories?post=9079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitestepona.eu\/es\/wp-json\/wp\/v2\/tags?post=9079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}