{"id":4422,"date":"2021-09-01T09:32:01","date_gmt":"2021-09-01T09:32:01","guid":{"rendered":"https:\/\/visitestepona.eu\/covid-19-massnahmen-in-estepona-und-la-fragata\/"},"modified":"2021-09-01T09:32:25","modified_gmt":"2021-09-01T09:32:25","slug":"covid-19-massnahmen-in-estepona-und-la-fragata","status":"publish","type":"post","link":"https:\/\/visitestepona.eu\/de\/covid-19-massnahmen-in-estepona-und-la-fragata\/","title":{"rendered":"Covid-19-Ma\u00dfnahmen in Estepona und La Fragata"},"content":{"rendered":"\n<p>Andalusien bietet allen nicht ans\u00e4ssigen internationalen Reisenden eine kostenlose Covid-Versicherung f\u00fcr den Aufenthalt in jeder Art von regulierter Einrichtung in der Region zwischen dem 1. Januar und dem 31. Dezember 2021.<\/p>\n\n<p>Erfahren Sie mehr: <a href=\"https:\/\/www.andalucia.org\/en\/travel-assistance-insurance?fbclid=IwAR2gtX7mfBU7uYCciz8Tb6nmLLziNDxLziwD2FWZOXnnBUBkREBF-WPaIRc\" class=\"rank-math-link\" target=\"_blank\" rel=\"noopener\">https:\/\/www.andalucia.org\/en\/travel-assistance-insurance?fbclid=IwAR2gtX7mfBU7uYCciz8Tb6nmLLziNDxLziwD2FWZOXnnBUBkREBF-WPaIRc<\/a><br\/><\/p>\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2021\/03\/COVID-19_Travel_Assistance_Insurance-1.pdf\">COVID-19_Travel_Assistance_Insurance-1<\/a><a href=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2021\/03\/COVID-19_Travel_Assistance_Insurance-1.pdf\" class=\"wp-block-file__button\" download=\"\">Herunterladen<\/a><\/div>\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2021\/03\/GENERAL_TERMS_AND_CONDITIONS_OF_THE_TRAVEL_ASSISTANCE_CONTRACT_JUNTA_DE_ANDALUCIA-1-1.pdf\">GENERAL_TERMS_AND_CONDITIONS_OF_THE_TRAVEL_ASSISTANCE_CONTRACT_JUNTA_DE_ANDALUCIA-1-1<\/a><a href=\"https:\/\/visitestepona.eu\/wp-content\/uploads\/2021\/03\/GENERAL_TERMS_AND_CONDITIONS_OF_THE_TRAVEL_ASSISTANCE_CONTRACT_JUNTA_DE_ANDALUCIA-1-1.pdf\" class=\"wp-block-file__button\" download=\"\">Herunterladen<\/a><\/div>\n\n<h2 class=\"wp-block-heading\">Andalusien (Update 30. April 2021)<\/h2>\n\n<p>WEITERLESEN: <strong> <a href=\"https:\/\/www.spanjevandaag.com\/28\/04\/2021\/einde-aan-provinciale-lockdowns-in-andalusie-en-verruiming-openingstijden\/\" target=\"_blank\" rel=\"noopener\">Ende der Provinzsperren in Andalusien und Verl\u00e4ngerung der \u00d6ffnungszeiten<\/a>\n  \n<\/strong><\/p>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Sperrung<\/td><td>Regional. Auch lokale Lockdowns (abh\u00e4ngig von der Corona-Inzidenz)<\/td><\/tr><tr><td>Ausgangssperre<\/td><td>Zwischen 11 P.m und 6.m.<\/td><\/tr><tr><td>Verpflegung<\/td><td>Ge\u00f6ffnet bis 23 Uhr. Interieur (75%) Exterieur (100%)<\/td><\/tr><tr><td>Gesch\u00e4fte<\/td><td>Ge\u00f6ffnet bis 22.30h.<\/td><\/tr><tr><td>Obligatorische Gesichtsmasken<\/td><td>Ja, immer unabh\u00e4ngig von der 1,5 m Entfernung<\/td><\/tr><tr><td>Gruppen<\/td><td>Max. 6 Pers. exterieur, 4 Pers. Interieur (Zuhause)<\/td><\/tr><\/tbody><\/table><\/figure>\n<p><br\/><br\/>I.v.m. die Ma\u00dfnahmen gegen Covid-19:<\/p>\n\n<p>Waschen Sie Ihre H\u00e4nde regelm\u00e4\u00dfig gut mit Seife.<br\/>Husten und Niesen in die Innenseite Ihres Ellenbogens<br\/>Verwenden Sie Papiertaschent\u00fccher und werfen Sie sie sofort weg (nicht in der Toilette)<\/p>\n\n<p><strong>L\u00fcften Sie die Wohnung regelm\u00e4\u00dfig, achten Sie darauf, dann keine Klimaanlage zu benutzen.<\/strong><\/p>\n\n<p>Wir haben die Reinigung der Wohnung so sorgf\u00e4ltig wie m\u00f6glich mit zertifizierten Reinigungsmitteln durchgef\u00fchrt. Oberfl\u00e4chen werden desinfiziert.<br\/><br\/><strong>Wenn Sie Ihre eigenen Desinfektionst\u00fccher verwenden, werfen Sie sie nicht in die Toilette, dies verstopft den Abfluss!<\/strong><\/p>\n\n<p>Alle Ma\u00dfnahmen basieren auf der Kenntnis der Fakten des Augenblicks nat\u00fcrlich vorbehaltlich \u00c4nderungen durch die CCAES (Spanisch RVIM), dann werden wir dies sofort anpassen.<\/p>\n\n<p>Vorerst ist die einzige Ma\u00dfnahme im La Fragata-Komplex, dass die Kapazit\u00e4t des Schwimmbades vor\u00fcbergehend angepasst wurde (max 75%), was bedeutet, dass bei uns maximal 48 Personen gleichzeitig sind. Wenn man sich den Pool anschaut, wird man erleben, dass in 10 Jahren noch nie 48 Personen gleichzeitig im Pool waren \ud83d\ude09 Anstatt sich nicht am Pool zu sonnen, gibt es vorerst keine Sonnenliegen. Auch bitte keine Materialien im Pool. Im Meer und am Strand gibt es daf\u00fcr nat\u00fcrlich viel Platz.  <br\/><br\/>Im Durchschnitt sind dies 0-12 Personen gleichzeitig. Oft gibt es nur 1 Familie.<br\/>Der Pool ist ger\u00e4umig, Abstand zu halten ist kein Problem.<\/p>\n\n<p>Es gibt viel Platz an den Str\u00e4nden. Es gibt 2 Str\u00e4nde zu Fu\u00df erreichbar. Die Leute fragen, ob Sie Hausschuhe oder Schuhe in Einrichtungen (Duschen, Strandbars, Gehwege) tragen m\u00f6chten.<\/p>\n\n<p>Seit Mitte Juli 2020 besteht unter anderem in Andalusien vorsorglich Gesichtsmasken auf der Stra\u00dfe und im \u00f6ffentlichen Bereich. Auch wenn Sie einen Abstand von 1,5 Metern halten k\u00f6nnen. Es ist, was es ist. Es wird nicht so schlimm sein, wie es w\u00e4hrend eines Aufenthalts in Estepona klingen mag.<br\/><br\/>Strand ist einfach, liegen \/ sitzen, fein, keine Mundmaske, gehen Sie spazieren, Mundmaske  <img loading=\"lazy\" decoding=\"async\" alt=\"&#x1F637;\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t32\/1\/16\/1f637.png\" width=\"16\" height=\"16\" title=\"\"><br\/>F\u00fcr die Gastronomie: Sie wohnen unter einem Dach, so dass Sie ohne Mundmaske gemeinsam am Tisch sitzen k\u00f6nnen.  <br\/><br\/>Die Sommerferien 2020 waren f\u00fcr alle, die sich anpassen, die Masken tragen, zun\u00e4chst nur in den L\u00e4den. Auch bewusst eine &#8222;andere&#8220; Art von Urlaub w\u00e4hlen, l\u00e4ngerer Tag am Strand, \u00f6fter auf einer Terrasse oder einem Restaurant, eine lauschige Bucht statt eines belebten Strandes, was \u00f6fter zu Hause auf der eigenen Terrasse oder im sch\u00f6nen Pool) &#8230;  <br\/>Es gibt und bleibt viele M\u00f6glichkeiten, diesem &#8222;Wahnsinn&#8220; zu entfliehen und trotzdem einen wundersch\u00f6nen Urlaub unter der Sonne <img loading=\"lazy\" decoding=\"async\" alt=\"&#x2600;&#xFE0F;\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t6d\/1\/16\/2600.png\" width=\"16\" height=\"16\" title=\"\"> zu genie\u00dfen, wenn Sie m\u00f6chten. Die durchschnittliche Urlaubszeit kann ohne Gesichtsmaske leicht 90% betragen.  <br\/><br\/>Getestet wurden die Kappen aus dem Supermarkt, die des Mercadonna atmen leichter als die des Lidl.  <br\/>Zum Beispiel k\u00f6nnen Sie trendige Gesichtsmasken bei <a href=\"https:\/\/www.facebook.com\/viavaiestepona1\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/viavaiestepona1\/<\/a> kaufen<br\/>Oder machen Sie sie selbst aus d\u00fcnner Baumwolle.<\/p>\n\n<p>Regeln \u00e4ndern sich in Spanien wie im Rest der Welt manchmal kurz zuvor. Wenn Sie auf dem Laufenden bleiben m\u00f6chten, ist ein Tipp, unserem NL-Botschafter auf Facebook zu folgen. Er schreibt jede Woche ein umfangreiches Update und alle Informationen werden zu 100% auf Fakten \u00fcberpr\u00fcft. Das ist auch unsere Quelle.  <a href=\"https:\/\/www.facebook.com\/AmbassadeurJanVersteeg\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/AmbassadeurJanVersteeg\/<\/a><\/p>\n\n<p>N\u00fctzlich, um die BZ-Reisehinweise genau im Auge zu behalten. Genauere Informationen finden Sie im Beitrag oben auf der Facebook-Seite &#8222;Niederl\u00e4ndische Botschaft in Spanien&#8220; <a href=\"https:\/\/www.facebook.com\/NLambassadeSpanje\/posts\/3494167223931649?__cft__%5B0%5D=AZW5BHrmgRP3Qj218BXEMMaKDWWuxvZHlEiBfz-JLxHDcLFBqrMPEWvnTB4j9MnHmObiI36YhcrBY_lZYQboVG_4wURrwwylkUo0EsTaiBC7-Jpc3atyf7RY-Yty7vBuidMhfWj3rLY47mIXjUZYN2NAHKBx3mPB9voKmcClhhPP5lA0xZMEvzDC9qS6fd9UN7dhIWvsruT7ZSPD56FFsi4HFF-XtsAcowAK_qvc3AgUSg&amp;__tn__=-UK-R\" target=\"_blank\" rel=\"noopener\">https:\/\/www.facebook.com\/NLambassadeSpanje\/posts\/3494167223931649?__tn__=K-R<\/a>. Dort finden Sie auch die Telefonnummern der verschiedenen spanischen Regionen, die Sie anrufen k\u00f6nnen, wenn Sie Symptome haben, die auf COVID19 hinweisen k\u00f6nnen.  <br\/><br\/>Sie k\u00f6nnen auch mehr \u00fcber das Formular lesen, das Sie ausf\u00fcllen m\u00fcssen, wenn Sie mit dem Flugzeug oder mit dem Boot nach Spanien reisen. Sie k\u00f6nnen dort auch Fragen stellen, obwohl ich auf Ihr Verst\u00e4ndnis hoffe, dass die Botschaft nicht in der Lage ist, Fragen zu bestimmten Str\u00e4nden, Museen, Bars und Restaurants in allen spanischen Regionen zu beantworten. Dazu kann es sinnvoll sein, sich die verschiedenen Websites und Facebook-Seiten von und f\u00fcr Niederl\u00e4ndischsprachige in bestimmten Regionen Spaniens anzusehen (Beispiele hierf\u00fcr finden Sie auch auf der oben genannten Seite). Auch dort werden viele Geschichten und Erlebnisse geteilt.  <\/p>\n\n<p>Aktualisierung der Testrichtlinie:<br\/><\/p>\n\n<p>Anpassungen der Testpflicht f\u00fcr Reisen in die Niederlande<br\/>Ab dem 3. M\u00e4rz werden die Regeln zur Covid-Testpflicht f\u00fcr Reisende, die mit Flugzeug, Schiff, Bus oder Bahn aus einem Hochrisikogebiet in die Niederlande reisen, erweitert. Reisende k\u00f6nnen aus einer der folgenden zwei Optionen w\u00e4hlen:<\/p>\n\n<p>1. Ein einziger negativer NAAT(PCR)-Test (siehe unten f\u00fcr die zul\u00e4ssigen Arten von Tests) von bis zu 12 Stunden bei der Abreise; ODER:<br\/>2. Ein doppelter Test: 1) einen negativen NAAT(PCR)-Test (siehe unten f\u00fcr die zul\u00e4ssigen Arten von Tests) von bis zu 72 Stunden bei der Ankunft, plus 2) ein negativer Schnelltest von bis zu 4 Stunden bei der Abreise.<\/p>\n\n<p>Zul\u00e4ssige Tests<br\/>&#8211; PCR oder RT PCR<br\/>&#8211; LAMP (Schleifenvermittelte isotherme Verst\u00e4rkung)<br\/>&#8211; TMA (Transkriptionsvermittelte Verst\u00e4rkung)<br\/>&#8211; mPOCT (Molekularer Point-of-Care-Test)<br\/>&#8211; NAAT (Nukleins\u00e4ure-Amplifikationstest)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andalusien bietet allen nicht ans\u00e4ssigen internationalen Reisenden eine kostenlose Covid-Versicherung f\u00fcr den Aufenthalt in jeder Art von regulierter Einrichtung in der Region zwischen dem 1. Januar und dem 31. Dezember 2021. Erfahren Sie mehr: https:\/\/www.andalucia.org\/en\/travel-assistance-insurance?fbclid=IwAR2gtX7mfBU7uYCciz8Tb6nmLLziNDxLziwD2FWZOXnnBUBkREBF-WPaIRc Andalusien (Update 30. April 2021) WEITERLESEN: Ende der Provinzsperren in Andalusien und Verl\u00e4ngerung der \u00d6ffnungszeiten Sperrung Regional. Auch lokale Lockdowns\u2026 <a href=\"https:\/\/visitestepona.eu\/de\/covid-19-massnahmen-in-estepona-und-la-fragata\/\">Read More &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":4424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[45],"tags":[],"class_list":["post-4422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"_links":{"self":[{"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/posts\/4422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/comments?post=4422"}],"version-history":[{"count":0,"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/posts\/4422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/media\/4424"}],"wp:attachment":[{"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/media?parent=4422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/categories?post=4422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitestepona.eu\/de\/wp-json\/wp\/v2\/tags?post=4422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}